{"id":8026,"date":"2020-01-07T13:03:08","date_gmt":"2020-01-07T12:03:08","guid":{"rendered":"https:\/\/udv.edu.gt\/noticia\/campus-huehuetenango-realiza-taller-de-coros\/"},"modified":"2020-01-07T13:03:08","modified_gmt":"2020-01-07T12:03:08","slug":"campus-huehuetenango-realiza-taller-de-coros","status":"publish","type":"noticia","link":"https:\/\/udv.edu.gt\/en\/noticia\/campus-huehuetenango-realiza-taller-de-coros\/","title":{"rendered":"Campus Huehuetenango realiza taller de coros"},"content":{"rendered":"<p>La m\u00fasica es un elemento presente en la vida de los seres humanos, en los momentos tristes y alegres. Los coros son agrupaciones que interpreta canciones de distintos g\u00e9neros, puede estar acompa\u00f1ados de instrumentos musicales o a capela.<\/p>\n<p>Con el objetivo de contagiar el entusiasmo por las agrupaciones corales, los alumnos de Universidad Da Vinci, Campus Huehuetenango, recibieron a los integrantes de CORODEMIA y del Coro de Universidad Da Vinci, Campus Guatemala, con quienes compartieron conocimientos y experiencias del \u00e1mbito coral.<\/p>\n<p>El maestro Fernando Archila, director del coro Da Vinci, realiz\u00f3 con 49 participantes ejercicios de respiraci\u00f3n, calentamiento de voz e interpretaci\u00f3n de varios temas musicales, de los cuales destac\u00f3 la participaci\u00f3n de CORODEMIA con la canci\u00f3n Siguanaba. La actividad se llev\u00f3 a cabo en el sal\u00f3n Vitruvio de esta casa de estudios.<\/p>\n<p>La m\u00fasica es una herramienta transformadora de la sociedad, en Universidad Da Vinci de Guatemala por medio de la Facultad de M\u00fasica, promueve la profesionalizaci\u00f3n de los m\u00fasicos guatemaltecos con el objetivo de contribuir al desarrollo del pa\u00eds.<\/p>","protected":false},"featured_media":6871,"template":"","categories":[],"tags":[],"class_list":["post-8026","noticia","type-noticia","status-publish","has-post-thumbnail","hentry"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/udv.edu.gt\/en\/wp-json\/wp\/v2\/noticia\/8026","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/udv.edu.gt\/en\/wp-json\/wp\/v2\/noticia"}],"about":[{"href":"https:\/\/udv.edu.gt\/en\/wp-json\/wp\/v2\/types\/noticia"}],"version-history":[{"count":0,"href":"https:\/\/udv.edu.gt\/en\/wp-json\/wp\/v2\/noticia\/8026\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/udv.edu.gt\/en\/wp-json\/wp\/v2\/media\/6871"}],"wp:attachment":[{"href":"https:\/\/udv.edu.gt\/en\/wp-json\/wp\/v2\/media?parent=8026"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/udv.edu.gt\/en\/wp-json\/wp\/v2\/categories?post=8026"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/udv.edu.gt\/en\/wp-json\/wp\/v2\/tags?post=8026"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}